{"id":11400,"date":"2016-08-30T16:45:45","date_gmt":"2016-08-30T21:45:45","guid":{"rendered":"http:\/\/arcoproperties.com\/?p=11400"},"modified":"2016-08-30T16:45:45","modified_gmt":"2016-08-30T21:45:45","slug":"evento-de-yoga-en-casco-viejo","status":"publish","type":"post","link":"https:\/\/arcoproperties.com\/es\/evento-de-yoga-en-casco-viejo\/","title":{"rendered":"Evento de Yoga en Casco Viejo"},"content":{"rendered":"<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div><p>Panama, Casco Viejo, Casco Antiguo<\/p>\n<p><a href=\"http:\/\/www.cascoyogapanama.com\/\">Casco Yoga<\/a>\u00a0 tiene todo el proximo mes clases y eventos divertidos!! Maya en su peri\u00f3dico nos brinda esta informacion; enterate de ellos:<\/p>\n<ul>\n<li>Despu\u00e9s de la increible\u00a0 respuesta que tuvo la Clase de Yoga por la Profesora Jakie, el 27 de Agosto, Casco decidi\u00f3 repetir este evento todos los primeros d\u00edas del mes. Comenzaremos desde el mes de Octubre porque Jakie est\u00e1 entrenando algunas semanas fuera del pa\u00eds.<\/li>\n<\/ul>\n<ul>\n<li>Este 1 de Septiembre empezaremos nuestro reto de 14 d\u00edas, luego del \u00e9xito que tuvo la primera vuelta en Junio. (Tambi\u00e9n esta disponible para cualquiera que tenga paquetes abiertos, se los podemos congelar por este tiempo).<\/li>\n<\/ul>\n<ul>\n<li>El 3 de Septiembre\u00a0 haremos nuestro primer Evento de\u00a0 RUN-YOGA-BEER!<\/li>\n<\/ul>\n<ul>\n<li>El 10 de Septiembre Leah Bess Murray estara impartiendo un hermoso taller en el estudio (precio especial para los participantes).<\/li>\n<\/ul>\n<ul>\n<li>Estamos trabajando muy de cerca con\u00a0 Leah para que organice un retiro de Yoga durante el Festival Surf&amp;Yoga en Bocas del Toro.\u00a0 Mantente en sintonia para mas informacion!!<\/li>\n<\/ul>\n<ul>\n<li>En adici\u00f3n a todo \u00e9sto este 17 de Septiembre tendremos otro Evento de RUN-YOGA-BEER , al final nos reuniremos en el estudio de Edwin y Maya para una peque\u00f1a celebraci\u00f3n por los novios.<\/li>\n<\/ul>\n<ul>\n<li>Sigue nuestro website\/redes sociales de manera constante para que te mantengas al tanto de los intinerarios y de mas informaci\u00f3n sobre los eventos. Hicimos un peque\u00f1o cambio en las clases considerando la hora del trafico los d\u00edas Jueves y Viernes ( Seran 30 minutos mas tarde, 5:30pm y 6:45pm)<\/li>\n<\/ul>\n<p><a href=\"http:\/\/arcoproperties.com\/wp-content\/uploads\/2016\/08\/Runyogabeercascoyoga.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-11397\" src=\"http:\/\/arcoproperties.com\/wp-content\/uploads\/2016\/08\/Runyogabeercascoyoga-300x300.png\" alt=\"Runyogabeercascoyoga\" width=\"300\" height=\"300\" srcset=\"https:\/\/arcoproperties.com\/wp-content\/uploads\/2016\/08\/Runyogabeercascoyoga-300x300.png 300w, https:\/\/arcoproperties.com\/wp-content\/uploads\/2016\/08\/Runyogabeercascoyoga-150x150.png 150w, https:\/\/arcoproperties.com\/wp-content\/uploads\/2016\/08\/Runyogabeercascoyoga.png 670w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Panama, Casco Viejo, Casco Antiguo Casco Yoga\u00a0 tiene todo el proximo mes clases y eventos divertidos!! Maya en su peri\u00f3dico nos brinda esta informacion; enterate de ellos: Despu\u00e9s de la increible\u00a0 respuesta que tuvo la Clase de Yoga por la Profesora Jakie, el 27 de Agosto, Casco decidi\u00f3 repetir este evento todos los primeros d\u00edas [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-11400","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/arcoproperties.com\/es\/wp-json\/wp\/v2\/posts\/11400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arcoproperties.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arcoproperties.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arcoproperties.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/arcoproperties.com\/es\/wp-json\/wp\/v2\/comments?post=11400"}],"version-history":[{"count":0,"href":"https:\/\/arcoproperties.com\/es\/wp-json\/wp\/v2\/posts\/11400\/revisions"}],"wp:attachment":[{"href":"https:\/\/arcoproperties.com\/es\/wp-json\/wp\/v2\/media?parent=11400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arcoproperties.com\/es\/wp-json\/wp\/v2\/categories?post=11400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arcoproperties.com\/es\/wp-json\/wp\/v2\/tags?post=11400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}